{"id":36802,"date":"2025-03-27T20:43:47","date_gmt":"2025-03-27T18:43:47","guid":{"rendered":"https:\/\/changlonet.com\/blog\/?p=36802"},"modified":"2025-03-27T20:45:28","modified_gmt":"2025-03-27T18:45:28","slug":"noctua-prepara-una-refrigeracin-lquida-sin-bomba","status":"publish","type":"post","link":"https:\/\/changlonet.com\/blog\/noctua-prepara-una-refrigeracin-lquida-sin-bomba\/","title":{"rendered":"Noctua prepara una refrigeraci&oacute;n l&iacute;quida sin bomba"},"content":{"rendered":"<p>Cuando montamos kits de refrigeraci\u00f3n l\u00edquida a\u00f1adimos un nuevo motor al sistema: el de la bomba de agua que mueve el l\u00edquido por el circuito. Esto genera por un lado algo m\u00e1s de ruido, tama\u00f1o y una posible fuente de aver\u00edas. Parece que Noctua quiere eliminar esa bomba con su dise\u00f1o de refrigeraci\u00f3n l\u00edquida que est\u00e1 desarrollando<\/p>\n<p><a href=\"https:\/\/changlonet.com\/blog\/wp-content\/uploads\/2025\/03\/refrigeracion-liquida-de-noctua-sin-bomba-de-agua_a.jpg\"><img fetchpriority=\"high\" decoding=\"async\" style=\"margin-right: auto; margin-left: auto; float: none; display: block; background-image: none;\" title=\"refrigeracion liquida de noctua sin bomba de agua_a\" src=\"https:\/\/changlonet.com\/blog\/wp-content\/uploads\/2025\/03\/refrigeracion-liquida-de-noctua-sin-bomba-de-agua_a_thumb.jpg\" alt=\"refrigeracion liquida de noctua sin bomba de agua_a\" width=\"689\" height=\"517\" border=\"0\" \/><\/a><\/p>\n<p><a href=\"https:\/\/changlonet.com\/blog\/wp-content\/uploads\/2025\/03\/refrigeracion-liquida-de-noctua-sin-bomba-de-agua_a.jpg\">\u00a0<\/a><\/p>\n<p>Llego a esta noticia <a href=\"https:\/\/www.guru3d.com\/story\/how-noctua-2026-cooling-system-will-work-without-a-pump\/\" target=\"_blank\" rel=\"noopener\">desde Guru3d<\/a> que me ha indicado el sitio <a href=\"https:\/\/www.gdm.or.jp\/crew\/2025\/0323\/580228\" target=\"_blank\" rel=\"noopener\">original de publicaci\u00f3n: gdm<\/a>.<\/p>\n<p>La idea en teor\u00eda es simple. El liquido que va dentro del circuito no es agua. En el disipador que est\u00e1 en contacto con el procesador tiene un sistema de termosif\u00f3n: el l\u00edquido por el calor del procesador se convierte en gas y asciende hac\u00eda el radiador. Una vez all\u00ed baja su temperatura y se licua, volviendo al disipador por el circuito de retorno ayudado por la gravedad, en forma de l\u00edquido para volver a empezar el proceso.<\/p>\n<p>Esto nos permite ahorrar piezas y ruidos. A cambio nos obliga a situar el radiado por encima del procesador. Es decir no podemos montar el radiador en el frontal o en la trasera de la caja, sino en la parte superior. Pero es un peque\u00f1o inconveniente que puede se aceptado por la mejora del ruido y de evitar motores que se puedan averiar.<\/p>\n<p>Lo malo es que la puesta a la venta del sistema se anuncia para el a\u00f1o pr\u00f3ximo, as\u00ed que nos queda todav\u00eda tiempo para poderlo ver en funcionamiento real.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando montamos kits de refrigeraci\u00f3n l\u00edquida a\u00f1adimos un nuevo motor al sistema: el de la bomba de agua que mueve el l\u00edquido por el circuito. Esto genera por un lado algo m\u00e1s de ruido, tama\u00f1o y una posible fuente de aver\u00edas. Parece que Noctua quiere eliminar esa bomba con su dise\u00f1o de refrigeraci\u00f3n l\u00edquida que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36801,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[8],"tags":[841,1920,2362,5498],"series":[],"class_list":["post-36802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hardware","tag-disipadores","tag-noctua","tag-refrigeracion-liquida","tag-diseno-sin-bomba"],"_links":{"self":[{"href":"https:\/\/changlonet.com\/blog\/wp-json\/wp\/v2\/posts\/36802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/changlonet.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/changlonet.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/changlonet.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/changlonet.com\/blog\/wp-json\/wp\/v2\/comments?post=36802"}],"version-history":[{"count":0,"href":"https:\/\/changlonet.com\/blog\/wp-json\/wp\/v2\/posts\/36802\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/changlonet.com\/blog\/wp-json\/wp\/v2\/media\/36801"}],"wp:attachment":[{"href":"https:\/\/changlonet.com\/blog\/wp-json\/wp\/v2\/media?parent=36802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/changlonet.com\/blog\/wp-json\/wp\/v2\/categories?post=36802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/changlonet.com\/blog\/wp-json\/wp\/v2\/tags?post=36802"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/changlonet.com\/blog\/wp-json\/wp\/v2\/series?post=36802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}